{"id":2973,"date":"2026-03-06T08:28:40","date_gmt":"2026-03-06T08:28:40","guid":{"rendered":"https:\/\/hauserhof.muwit.net\/privacy\/"},"modified":"2026-06-22T12:30:55","modified_gmt":"2026-06-22T12:30:55","slug":"privacy","status":"publish","type":"page","link":"https:\/\/www.hauserhof.net\/it\/privacy\/","title":{"rendered":"privacy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2973\" class=\"elementor elementor-2973 elementor-1181\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-deedb05 e-con-full e-flex e-con e-parent\" data-id=\"deedb05\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-322191d e-con-full e-flex e-con e-child\" data-id=\"322191d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c482331 slider-main elementor--h-position-center elementor--v-position-middle elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"c482331\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;dots&quot;,&quot;transition&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-6273906 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"hauserhof-unterwegs-sommer-header\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e972296 e-con-full e-flex e-con e-parent\" data-id=\"e972296\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-2a50db5 e-con-full e-flex e-con e-child\" data-id=\"2a50db5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc8b5a1 h2p animated-slow elementor-widget elementor-widget-heading\" data-id=\"dc8b5a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Privacy &amp; Cookies<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79ef84c whitelink textwidth p-bt-s p-r-s-des p-l-m-des animated-slow elementor-widget elementor-widget-text-editor\" data-id=\"79ef84c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>INFORMATIVA SUL TRATTAMENTO DEI DATI PERSONALI<br \/><\/strong><strong>Informativa ai sensi degli artt. 12, 13 e 14 del Regolamento UE 679\/2016<\/strong><\/p><p><strong>Titolare del trattamento<\/strong><\/p><p>Hauserhof<br \/>Sauders 3<br \/>39040 Villanders<br \/>Alto Adige | Italia<\/p><div><p><a href=\"mailto:info@hauserhof.net\">info@hauserhof.net<\/a><br \/><a href=\"tel:+393408432722\">+39 340 843 2722<\/a><br \/><a href=\"https:\/\/hauserhof.net\">hauserhof.net<\/a><\/p><\/div><p><strong>Informazioni sulla privacy \u2013 Sito web<\/strong><\/p><p>Gentile visitatore,<br \/>siamo lieti di informarLa su come vengono trattati i Suoi dati personali quando visita il nostro sito web. Da questa informativa potr\u00e0 vedere quali sono i diritti che pu\u00f2 esercitare in qualit\u00e0 di interessato.<br \/>I Suoi dati personali saranno trattati in conformit\u00e0 al Regolamento UE 2016\/679 (Regolamento generale sulla protezione dei dati) ed alla legislazione nazionale in materia di protezione dei dati.<br \/>L&#8217;utilizzo del sito web implica l&#8217;accettazione della presente informativa sulla privacy, in caso contrario Le chiediamo di non continuare ad utilizzare questo sito web.<br \/>Desideriamo inoltre informarLa che i link presenti sul nostro sito web sono stati da noi accuratamente selezionati e controllati. Poich\u00e9 i siti ad esso collegati possono essere soggetti ad aggiornamenti che avvengono a nostra insaputa ed i loro contenuti possono cambiare continuamente, non ci assumiamo alcuna responsabilit\u00e0 per essi.<\/p><p><strong>Finalit\u00e0 del trattamento dei dati personali:<\/strong><br \/>Per garantire la funzionalit\u00e0 del sito web nonch\u00e9 per scopi statistici, vengono trattati dati tecnici con potenziale riferimento personale, come ad esempio l&#8217;indirizzo IP, l&#8217;ora degli accessi, il nome del dominio e dati simili. Inoltre, il gestore del sito web ha un interesse legittimo (art. 6f GDPR) a fornire un sito web visivamente accattivante e una piacevole esperienza d&#8217;uso. Previo consenso (art. 6a GDPR), \u00e8 inoltre possibile analizzare il comportamento degli utenti e perseguire finalit\u00e0 di marketing.<br \/>Lo scopo principale del trattamento dei dati \u00e8 la fornitura del nostro sito web e dei suoi contenuti, nonch\u00e9 l&#8217;adempimento delle richieste dell&#8217;utente.<br \/>I dati personali vengono inoltre trattati per offrire diversi servizi:<\/p><p><strong>Modulo di contatto<\/strong><br \/>Il visitatore del sito web pu\u00f2 contattare l&#8217;azienda utilizzando il modulo di contatto. A tal fine, i dati personali inseriti saranno trattati per rispondere alla richiesta. \u00c8 disponibile un consenso esplicito al trattamento dei dati nel modulo di contatto.<\/p><p><strong>Trasmissione di categorie particolari di dati personali<\/strong><br \/>La preghiamo di non trasmettere dati sensibili (dati personali di categorie speciali \u2013 art. 9 e art. 10 GDPR) tramite il sito web, ad esempio utilizzando il modulo di contatto.<\/p><p><strong>Base giuridica del trattamento dei dati<\/strong><br \/>La base giuridica principale per il trattamento \u00e8 l&#8217;art. 6b) GDPR (adempimento di misure pre-contrattuali\/contrattuali) e l&#8217;art. 6f) GDPR (funzionalit\u00e0 del sito web) nonch\u00e9 il consenso ottenuto, se fornito da Lei (art. 6a GDPR).<\/p><p><strong>Cookies<\/strong><br \/>Il nostro sito web utilizza cookies, grazie ai quali i dati personali possono essere elaborati.<\/p><p>Esistono quattro categorie di cookies:<\/p><p>Cookies strettamente necessari \u2013 per la funzionalit\u00e0 di base del sito web<br \/>Cookies funzionali \u2013 per garantire le prestazioni ottimali del sito web, ad esempio il salvataggio della selezione della lingua<br \/>Cookies di prestazione \u2013 per migliorare l&#8217;esperienza dell&#8217;utente e per elaborare informazioni sull&#8217;utilizzo del sito web, ad esempio per misurare i tempi di caricamento<br \/>Cookies di marketing \u2013 per la raccolta del comportamento e degli interessi dell&#8217;utente a fini di marketing, ad esempio per l&#8217;inserimento di pubblicit\u00e0 personalizzata<br \/>I cookies non essenziali sono disattivati per impostazione predefinita sui nostri siti web e vengono attivati solo se l&#8217;utente ha dato il proprio esplicito consenso.<\/p><p>La maggior parte dei cookies utilizzati sono &#8220;cookies di sessione&#8221; che vengono eliminati dopo la chiusura del browser. Altri cookies vengono memorizzati pi\u00f9 a lungo, ad esempio per visualizzare la lingua corretta alla successiva visita del sito web.<br \/>Per tutti i cookies che non sono soggetti ad un interesse legittimo del gestore del sito web (art. 6f) GDPR), Le verr\u00e0 chiesto esplicitamente il consenso.<\/p><p>\u00c8 possibile cancellare i cookies in qualsiasi momento, a seconda del browser utilizzato, cliccando di solito sui 3 puntini\/strisce in alto a destra e poi aprendo le impostazioni, digitando cookie nel campo di ricerca e selezionando: elimina cookie\/elimina dati del browser.<\/p><p><strong>Fornitura dei dati<\/strong><br \/>Il conferimento dei dati \u00e8 volontario (ad eccezione del trattamento dei dati di navigazione) e non \u00e8 richiesto dalla legge. Tuttavia, il mancato conferimento pu\u00f2 comportare la limitazione dell&#8217;uso del sito web e dei servizi offerti.<\/p><p><strong>Trasferimento dei dati a terzi<\/strong><br \/>I Suoi dati possono essere trasmessi a terzi se necessario, ma solo nell&#8217;ambito del nostro rapporto commerciale, ad esempio per l&#8217;adempimento della Sua richiesta o, se applicabile, per l&#8217;esecuzione di pagamenti tramite terzi e per l&#8217;adempimento di obblighi legali. In linea di principio, i Suoi dati non saranno trasferiti in Paesi extra UE senza il Suo esplicito consenso. Lo stesso vale anche per l&#8217;uso della profilazione e delle decisioni automatizzate.<\/p><p><strong>Hosting del sito web<\/strong><br \/>Questo sito web \u00e8 ospitato da un fornitore di servizi esterno. A tal fine, il fornitore esterno riceve i dati personali raccolti sul sito web. La base giuridica \u00e8 costituita dall&#8217;art. 6b) GDPR (misure pre-contrattuali\/contrattuali) e dall&#8217;art. 6f) (garanzia del corretto funzionamento degli strumenti presenti sul nostro sito web).<\/p><p><strong>Servizi Google<\/strong><br \/>Il nostro sito web utilizza i servizi dell&#8217;operatore Google Ireland Limited (&#8220;Google&#8221;), Gordon House, Barrow Street, Dublino 4, Irlanda.<br \/>Google pu\u00f2 quindi, in determinate circostanze, trattare informazioni e dati personali. Si noti che le autorit\u00e0 americane potrebbero teoricamente accedere a questi dati a causa della legislazione americana (in particolare il Cloud Act). Le informazioni sul quadro giuridico per il trasferimento dei dati sono disponibili sul sito https:\/\/policies.google.com\/privacy\/frameworks.<\/p><p><strong>Previo consenso: Google Tag Manager<\/strong><br \/>Il nostro sito web utilizza Google Tag Manager. Il fornitore \u00e8 Google Ireland Limited (&#8220;Google&#8221;), Gordon House, Barrow Street, Dublino 4, Irlanda.<br \/>Google Tag Manager semplifica l&#8217;integrazione dei codici di tracciamento. Inoltre, offre agli operatori del sito la possibilit\u00e0 di apportare modifiche che vengono applicate automaticamente alle pagine senza dover adattare il codice sorgente.<br \/>Google Tag Manager pu\u00f2 comunicare con i server di Tag Manager, nel corso dei quali possono essere elaborati dati personali quando viene attivato un tag (ad esempio, l&#8217;indirizzo IP).<br \/>Prima dell&#8217;attivazione di Google Tag Manager Le verr\u00e0 chiesto esplicitamente il consenso. La base giuridica \u00e8 l&#8217;art. 6a) GDPR.<br \/>Informazioni dettagliate sono disponibili all&#8217;indirizzo: https:\/\/policies.google.com\/privacy<\/p><p><strong>Previo consenso: Analisi web \u2013 Google Analytics<\/strong><br \/>Il nostro sito web utilizza le funzioni del servizio di analisi web Google Analytics. Il fornitore \u00e8 Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA.<br \/>Le informazioni ottenute attraverso i cookies sull&#8217;utilizzo del sito web da parte dell&#8217;utente (compreso l&#8217;indirizzo IP) possono essere trasferite ad un server di Google negli Stati Uniti. L&#8217;informativa completa \u00e8 disponibile nella privacy policy di Google: https:\/\/support.google.com\/analytics\/answer\/6004245?hl=it<br \/>Utilizziamo Google Analytics come strumento di analisi per monitorare le prestazioni del nostro sito web, analizzare il comportamento dei clienti e adottare le misure appropriate.<br \/>Prima dell&#8217;attivazione di Google Analytics Le verr\u00e0 chiesto esplicitamente il Suo consenso. La base giuridica \u00e8 l&#8217;art. 6a) GDPR.<br \/>\u00c8 inoltre possibile impedire la raccolta e l&#8217;elaborazione dei dati descritti da parte di Google scaricando e installando il plug-in del browser disponibile al seguente link: https:\/\/tools.google.com\/dlpage\/gaoptout<\/p><p><strong>Previo consenso: Facebook Pixel<\/strong><br \/>Il nostro sito web utilizza il cosiddetto &#8220;Facebook Pixel&#8221; del social network Facebook, gestito da Facebook Inc. o, se \u00e8 residente nell&#8217;UE, da Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublino 2, Irlanda.<br \/>Quando visita il sito web, viene stabilita una connessione diretta con il server di Facebook tramite il Facebook Pixel. Questo trasmette al server la Sua visita e Facebook pu\u00f2, in determinate circostanze, assegnare le informazioni al Suo account personale di Facebook. Possiamo cos\u00ec monitorare l&#8217;effetto delle campagne pubblicitarie.<br \/>Non si pu\u00f2 escludere che le informazioni vengano trasmesse a server di Paesi extra UE.<br \/>Se l&#8217;utente acconsente all&#8217;utilizzo del Facebook Pixel, questo verr\u00e0 integrato da Facebook e un cookie verr\u00e0 memorizzato sul dispositivo dell&#8217;utente come descritto sopra. Quando si accede a Facebook, le offerte visitate vengono registrate nel profilo dell&#8217;utente. I dati vengono anonimizzati per noi, ma Facebook ha la possibilit\u00e0 di trattarli.<br \/>Per ulteriori informazioni sulla raccolta e sull&#8217;utilizzo dei dati da parte di Facebook, nonch\u00e9 sui diritti dell&#8217;utente e sulle possibilit\u00e0 di proteggere la propria privacy, si prega di consultare l&#8217;informativa sulla privacy di Facebook all&#8217;indirizzo: https:\/\/www.facebook.com\/business\/m\/privacy-and-data<br \/>Prima dell&#8217;attivazione di Facebook Pixel Le verr\u00e0 chiesto esplicitamente il consenso. La base giuridica \u00e8 l&#8217;art. 6a) GDPR.<\/p><p><strong>Crittografia SSL<\/strong><br \/>Questo sito utilizza la crittografia SSL per motivi di sicurezza della trasmissione, ad esempio per le richieste nei moduli di contatto. La crittografia SSL attiva viene utilizzata per criptare la trasmissione dei dati che ci vengono inviati.<\/p><p><strong>Visitatori minorenni<\/strong><br \/>Questo sito web non \u00e8 destinato all&#8217;uso da parte di minori. Pertanto, non raccogliamo e memorizziamo dati di visitatori minorenni (se non involontariamente).<\/p><p><strong>Durata della conservazione dei dati<\/strong><br \/>I Suoi dati vengono conservati secondo gli obblighi di conservazione previsti dalla legge e gli obblighi legali a noi applicabili.<\/p><p><strong>Riferimenti ai diritti degli interessati<\/strong><br \/>L&#8217;interessato ha il diritto di ottenere dal titolare del trattamento la conferma dell&#8217;esistenza o meno dei dati personali che lo riguardano; in tal caso, ha il <strong>diritto di accesso<\/strong> ai dati personali e alle informazioni di cui all&#8217;art. 15 GDPR.<br \/>L&#8217;interessato ha il diritto di esigere che il titolare del trattamento corregga immediatamente i dati personali inesatti che lo riguardano e, se necessario, completi i dati personali incompleti (<strong>rettifica<\/strong>, art. 16 GDPR).<br \/>L&#8217;interessato ha il diritto di esigere la cancellazione immediata dei dati personali che lo riguardano, qualora ricorra uno dei motivi di cui all&#8217;art. 17 GDPR, ad esempio se i dati non sono pi\u00f9 necessari per gli scopi per i quali sono stati raccolti (<strong>diritto alla cancellazione<\/strong>).<br \/>L&#8217;interessato ha il diritto di richiedere al titolare del trattamento di limitare il trattamento se \u00e8 soddisfatta una delle condizioni di cui all&#8217;art. 18 GDPR, ad esempio se l&#8217;interessato si \u00e8 opposto al trattamento.<br \/>L&#8217;interessato ha il diritto di ricevere in un formato strutturato, di uso comune e leggibile da dispositivo automatico i dati personali che lo riguardano e ha il diritto di trasmetterli a un altro titolare del trattamento senza impedimenti, ad esempio se il trattamento si basa sul consenso e viene effettuato con mezzi automatizzati (<strong>diritto alla portabilit\u00e0 dei dati<\/strong>, art. 20 GDPR).<br \/>L&#8217;interessato ha il diritto di opporsi in qualsiasi momento al trattamento dei dati personali che lo riguardano per motivi connessi alla sua situazione particolare. Il titolare del trattamento non tratta pi\u00f9 i dati personali, a meno che non dimostri l&#8217;esistenza di motivi legittimi cogenti per procedere al trattamento che prevalgono sugli interessi, sui diritti e sulle libert\u00e0 dell&#8217;interessato, oppure per l&#8217;accertamento, l&#8217;esercizio o la difesa di un diritto in sede giudiziaria (art. 21 GDPR).<br \/>Fatto salvo ogni altro ricorso amministrativo o giurisdizionale, l&#8217;interessato che ritenga che il trattamento che lo riguarda violi il presente regolamento ha il diritto di proporre reclamo a un&#8217;autorit\u00e0 di controllo (art. 77 GDPR). In Italia, l&#8217;autorit\u00e0 di vigilanza competente \u00e8 il Garante per la protezione dei dati personali.<\/p><p>La presente informativa sulla protezione dei dati pu\u00f2 essere aggiornata in qualsiasi momento.<\/p><p><strong>South Tyrol Guest Pass<\/strong><\/p><p><strong>Finalit\u00e0<\/strong><br \/>I dati personali trasmessi vengono inoltrati all&#8217;ufficio di coordinamento centrale del Guest Pass al fine di consentire la creazione e l&#8217;utilizzo del Guest Pass e di fornire i servizi ad esso associati.<\/p><p><strong>Destinatari<\/strong><br \/>In relazione all&#8217;emissione del Guest Pass, i Suoi dati verranno trasmessi al Consorzio per la Mobilit\u00e0 con P. IVA 02735170215, che, in qualit\u00e0 di gestore del Guest Pass e ufficio di coordinamento centrale, assume il ruolo di titolare autonomo del trattamento dei dati trasmessi. Per ulteriori informazioni sul trattamento a cui i dati sono soggetti, \u00e8 possibile inviare una e-mail a privacy@moko.bz.it.<\/p><p><strong>Base giuridica<\/strong><br \/>La base giuridica per il trattamento \u00e8 l&#8217;art. 6, par. 1, lett. b) del GDPR.<\/p><p><strong>Termini e condizioni<\/strong><br \/>Al completamento del contratto di soggiorno, all&#8217;ospite viene rilasciato il South Tyrol Alto Adige Guest Pass (di seguito &#8220;Guest Pass&#8221;), che ai sensi della delibera della Giunta Provinciale dell&#8217;Alto Adige n. 732\/2022 \u00e8 valido per l&#8217;intera durata del soggiorno, dalle ore 00:00 del giorno di arrivo alle ore 24:00 del giorno di partenza.<br \/>Il Guest Pass include l&#8217;utilizzo di tutti i mezzi di trasporto pubblico nell&#8217;area del consorzio S\u00fcdtirolMobil, nonch\u00e9 servizi aggiuntivi che possono variare a seconda dell&#8217;organizzazione turistica. Informazioni dettagliate sono disponibili su: suedtirol-guestpass.info.<br \/>L&#8217;unico gestore del Guest Pass valido in tutto l&#8217;Alto Adige \u00e8 il Consorzio per la Mobilit\u00e0, nominato ufficio di coordinamento centrale ai sensi della suddetta delibera provinciale dall&#8217;Associazione Provinciale delle Organizzazioni Turistiche dell&#8217;Alto Adige (LTS) il 16.11.2022. I dettagli dei servizi aggiuntivi associati al Guest Pass e le condizioni di utilizzo vengono comunicati dal terzo incaricato dell&#8217;emissione e della gestione del Guest Pass. Informazioni dettagliate sono disponibili su: suedtirol-guestpass.info.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Privacy &amp; Cookies INFORMATIVA SUL TRATTAMENTO DEI DATI PERSONALIInformativa ai sensi degli artt. 12, 13 e 14 del Regolamento UE 679\/2016 Titolare del trattamento HauserhofSauders 339040 VillandersAlto Adige | Italia info@hauserhof.net+39 340 843 2722hauserhof.net Informazioni sulla privacy \u2013 Sito web Gentile visitatore,siamo lieti di informarLa su come vengono trattati i Suoi dati personali quando visita [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2973","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>privacy - Hauserhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hauserhof.net\/it\/privacy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"privacy - Hauserhof\" \/>\n<meta property=\"og:description\" content=\"Privacy &amp; Cookies INFORMATIVA SUL TRATTAMENTO DEI DATI PERSONALIInformativa ai sensi degli artt. 12, 13 e 14 del Regolamento UE 679\/2016 Titolare del trattamento HauserhofSauders 339040 VillandersAlto Adige | Italia info@hauserhof.net+39 340 843 2722hauserhof.net Informazioni sulla privacy \u2013 Sito web Gentile visitatore,siamo lieti di informarLa su come vengono trattati i Suoi dati personali quando visita [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hauserhof.net\/it\/privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"Hauserhof\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T12:30:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/privacy\\\/\",\"url\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/privacy\\\/\",\"name\":\"privacy - Hauserhof\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/#website\"},\"datePublished\":\"2026-03-06T08:28:40+00:00\",\"dateModified\":\"2026-06-22T12:30:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/privacy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/privacy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/privacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/\",\"name\":\"Hauserhof\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/#organization\",\"name\":\"Hauserhof\",\"url\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hauserhof.net\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hauserhof_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.hauserhof.net\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hauserhof_logo.png\",\"width\":190,\"height\":79,\"caption\":\"Hauserhof\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hauserhof.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"privacy - Hauserhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hauserhof.net\/it\/privacy\/","og_locale":"it_IT","og_type":"article","og_title":"privacy - Hauserhof","og_description":"Privacy &amp; Cookies INFORMATIVA SUL TRATTAMENTO DEI DATI PERSONALIInformativa ai sensi degli artt. 12, 13 e 14 del Regolamento UE 679\/2016 Titolare del trattamento HauserhofSauders 339040 VillandersAlto Adige | Italia info@hauserhof.net+39 340 843 2722hauserhof.net Informazioni sulla privacy \u2013 Sito web Gentile visitatore,siamo lieti di informarLa su come vengono trattati i Suoi dati personali quando visita [&hellip;]","og_url":"https:\/\/www.hauserhof.net\/it\/privacy\/","og_site_name":"Hauserhof","article_modified_time":"2026-06-22T12:30:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hauserhof.net\/it\/privacy\/","url":"https:\/\/www.hauserhof.net\/it\/privacy\/","name":"privacy - Hauserhof","isPartOf":{"@id":"https:\/\/www.hauserhof.net\/it\/#website"},"datePublished":"2026-03-06T08:28:40+00:00","dateModified":"2026-06-22T12:30:55+00:00","breadcrumb":{"@id":"https:\/\/www.hauserhof.net\/it\/privacy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hauserhof.net\/it\/privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hauserhof.net\/it\/privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.hauserhof.net\/it\/"},{"@type":"ListItem","position":2,"name":"privacy"}]},{"@type":"WebSite","@id":"https:\/\/www.hauserhof.net\/it\/#website","url":"https:\/\/www.hauserhof.net\/it\/","name":"Hauserhof","description":"","publisher":{"@id":"https:\/\/www.hauserhof.net\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hauserhof.net\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hauserhof.net\/it\/#organization","name":"Hauserhof","url":"https:\/\/www.hauserhof.net\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hauserhof.net\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.hauserhof.net\/wp-content\/uploads\/2026\/02\/hauserhof_logo.png","contentUrl":"https:\/\/www.hauserhof.net\/wp-content\/uploads\/2026\/02\/hauserhof_logo.png","width":190,"height":79,"caption":"Hauserhof"},"image":{"@id":"https:\/\/www.hauserhof.net\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hauserhof.net\/it\/wp-json\/wp\/v2\/pages\/2973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hauserhof.net\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hauserhof.net\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hauserhof.net\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hauserhof.net\/it\/wp-json\/wp\/v2\/comments?post=2973"}],"version-history":[{"count":0,"href":"https:\/\/www.hauserhof.net\/it\/wp-json\/wp\/v2\/pages\/2973\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hauserhof.net\/it\/wp-json\/wp\/v2\/media?parent=2973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}